{"id":5537,"date":"2024-11-28T12:38:58","date_gmt":"2024-11-28T05:38:58","guid":{"rendered":"https:\/\/www.theoneenterprise.com\/?p=5537"},"modified":"2024-11-28T12:38:58","modified_gmt":"2024-11-28T05:38:58","slug":"weare_281124","status":"publish","type":"post","link":"https:\/\/www.theoneenterprise.com\/en\/weare_281124\/","title":{"rendered":"\u0e1b\u0e31\u0e07\u0e44\u0e21\u0e48\u0e2b\u0e22\u0e38\u0e14! \u0e0b\u0e35\u0e23\u0e35\u0e2a\u0e4c \u201cWe Are \u0e04\u0e37\u0e2d\u0e40\u0e23\u0e32\u0e23\u0e31\u0e01\u0e01\u0e31\u0e19\u201d  \u0e04\u0e27\u0e49\u0e32\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25 \u201cD-Series\u201d \u0e08\u0e32\u0e01\u0e40\u0e27\u0e17\u0e35 \u201cDailynews Awards 2024\u201d"},"content":{"rendered":"<p><span lang=\"TH\">\u0e01\u0e23\u0e30\u0e41\u0e2a\u0e1b\u0e31\u0e07\u0e41\u0e25\u0e30\u0e41\u0e23\u0e07\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e44\u0e21\u0e48<wbr \/>\u0e2b\u0e22\u0e38\u0e14 \u0e41\u0e21\u0e49\u0e27\u0e48\u0e32\u0e0b\u0e35\u0e23\u0e35\u0e2a\u0e4c\u0e08\u0e30\u0e08\u0e1a\u0e44\u0e1b\u0e41\u0e25\u0e49\u0e27 \u0e41\u0e15\u0e48\u0e17\u0e35\u0e21\u0e19\u0e31\u0e01\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e38\u0e14\u0e2e\u0e2d\u0e15\u0e01\u0e47\u0e40\u0e14\u0e34<wbr \/>\u0e19\u0e17\u0e32\u0e07\u0e44\u0e1b\u0e1e\u0e1a\u0e01\u0e31\u0e1a\u0e41\u0e1f\u0e19 \u0e46 \u0e17\u0e31\u0e48\u0e27\u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22 \u0e01\u0e31\u0e1a\u0e07\u0e32\u0e19<b>\u00a0<\/b><\/span><b>\u201cWE ARE FOREVER ASIA TOUR\u201d\u00a0<\/b>WE ARE&#8230;\u00a0<span lang=\"TH\">\u0e40\u0e1e\u0e23\u0e32\u0e30\u0e04\u0e27\u0e32\u0e21\u0e23\u0e31\u0e01\u0e17\u0e35\u0e48\u0e17\u0e38\u0e01\u0e04\u0e19\u0e21\u0e2d\u0e1a\u0e43\u0e2b\u0e49 \u0e08\u0e30\u0e19\u0e32\u0e19\u0e15\u0e25\u0e2d\u0e14\u0e01\u0e32\u0e25<b>\u00a0<\/b>\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e0b\u0e35\u0e23\u0e35\u0e2a\u0e4c<b>\u00a0\u201c<\/b><\/span><b>We Are\u00a0<span lang=\"TH\">\u0e04\u0e37\u0e2d\u0e40\u0e23\u0e32\u0e23\u0e31\u0e01\u0e01\u0e31\u0e19\u201d<\/span><\/b><span lang=\"TH\">\u00a0\u0e08\u0e32\u0e01\u00a0<\/span><b><span lang=\"TH\">\u201c<\/span><\/b><b>GMMTV<span lang=\"TH\">\u201d<\/span><\/b><span lang=\"TH\">\u00a0\u0e04\u0e2d\u0e19\u0e40\u0e17\u0e19\u0e15\u0e4c\u0e42\u0e1e\u0e23\u0e44\u0e27\u0e40\u0e14\u0e2d\u0e23\u0e4c\u0e0a\u0e31\u0e49\u0e19\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e40\u0e21\u0e37<wbr \/>\u0e2d\u0e07\u0e44\u0e17\u0e22\u00a0\u0e43\u0e19\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17<b>\u00a0\u201c\u0e40\u0e14\u0e2d\u0e30 \u0e27\u0e31\u0e19 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 (\u0e21\u0e2b\u0e32\u0e0a\u0e19)\u201d<\/b>\u00a0\u0e17\u0e35\u0e48\u0e1c\u0e25\u0e34\u0e15\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48<wbr \/>\u0e2d\u0e07 \u0e08\u0e19\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e19\u0e34\u0e22\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e0a\u0e37\u0e48<wbr \/>\u0e19\u0e0a\u0e2d\u0e1a\u0e17\u0e31\u0e49\u0e07\u0e08\u0e32\u0e01\u0e41\u0e1f\u0e19 \u0e46 \u0e0a\u0e32\u0e27\u0e44\u0e17\u0e22\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e0a\u0e32\u0e15\u0e34 <\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-5539 aligncenter\" src=\"https:\/\/www.theoneenterprise.com\/wp-content\/uploads\/2024\/11\/S__11436148.jpg\" alt=\"\" width=\"1146\" height=\"1428\" srcset=\"https:\/\/www.theoneenterprise.com\/wp-content\/uploads\/2024\/11\/S__11436148.jpg 1146w, https:\/\/www.theoneenterprise.com\/wp-content\/uploads\/2024\/11\/S__11436148-768x957.jpg 768w, https:\/\/www.theoneenterprise.com\/wp-content\/uploads\/2024\/11\/S__11436148-10x12.jpg 10w\" sizes=\"auto, (max-width: 1146px) 100vw, 1146px\" \/><\/p>\n<p><span lang=\"TH\">\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14\u0e40\u0e02\u0e49\u0e32\u0e15\u0e32\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e04\u0e27\u0e49\u0e32\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u00a0<b>\u201c<\/b><\/span><b>D-Series<span lang=\"TH\">\u201d\u00a0<\/span><\/b><span lang=\"TH\">\u0e08\u0e32\u0e01\u0e40\u0e27\u0e17\u0e35<b>\u00a0\u201c<\/b><\/span><b>Dailynews Awards 2024<span lang=\"TH\">\u201d<\/span><\/b><span lang=\"TH\">\u00a0\u0e08\u0e31\u0e14\u0e42\u0e14\u0e22\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e40\u0e14\u0e25\u0e34\u0e19\u0e34\u0e27\u0e2a\u0e4c \u0e0b\u0e36\u0e48\u0e07\u0e19\u0e31\u0e01\u0e41\u0e2a\u0e14\u0e07\u0e15\u0e34\u0e14\u0e20\u0e32\u0e23\u0e01\u0e34\u0e08\u0e44\u0e21\u0e48<wbr \/>\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e44\u0e1b\u0e23\u0e31\u0e1a\u0e44\u0e14\u0e49\u0e14\u0e49\u0e27\u0e22\u0e15\u0e19\u0e40\u0e2d\u0e07 \u0e42\u0e14\u0e22\u0e21\u0e35<\/span><b><span lang=\"TH\">\u00a0\u201c\u0e1b\u0e2d\u0e19\u0e14\u0e4c \u0e13\u0e23\u0e32\u0e27\u0e34\u0e0a\u0e0d\u0e4c \u0e40\u0e25\u0e34\u0e28\u0e23\u0e31\u0e15\u0e19\u0e4c\u0e42\u0e01\u0e2a\u0e38\u0e21\u0e20\u0e4c, \u0e20\u0e39\u0e27\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e15\u0e31\u0e49\u0e07\u0e28\u0e31\u0e01\u0e14\u0e34\u0e4c\u0e22\u0e37\u0e19\u201d<\/span><\/b><span lang=\"TH\">\u00a0<\/span><span lang=\"TH\">\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e2a\u0e48\u0e07\u0e04\u0e25\u0e34\u0e1b\u0e01\u0e25\u0e48\u0e32\u0e27\u0e02\u0e2d\u0e1a\u0e04\u0e38\u0e13<\/span><span lang=\"TH\">\u00a0\u0e0b\u0e36\u0e48\u0e07\u0e01\u0e32\u0e23\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e43\u0e19\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49<wbr \/>\u0e17\u0e31\u0e49\u0e07\u0e19\u0e31\u0e01\u0e41\u0e2a\u0e14\u0e07\u0e41\u0e25\u0e30\u0e17\u0e35\u0e21\u0e07\u0e32\u0e19\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e14\u0e35<wbr \/>\u0e43\u0e08\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e32\u0e01 \u0e16\u0e37\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e23\u0e07\u0e1c\u0e25\u0e31\u0e01\u0e14\u0e31\u0e19\u0e43\u0e2b\u0e49\u0e21\u0e35\u0e01\u0e33\u0e25\u0e31<wbr \/>\u0e07\u0e43\u0e08\u0e43\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e40\u0e1e\u0e37\u0e48<wbr \/>\u0e2d\u0e43\u0e2b\u0e49\u0e14\u0e35\u0e22\u0e34\u0e48\u0e07\u0e02\u0e36\u0e49\u0e19 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e02\u0e2d\u0e1a\u0e04\u0e38\u0e13\u0e41\u0e1f\u0e19 \u0e46 \u0e17\u0e35\u0e48\u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e14\u0e49\u0e27\u0e22\u0e14\u0e35\u0e21\u0e32\u0e15\u0e25\u0e2d\u0e14 \u0e13 \u0e2a\u0e40\u0e1f\u0e35\u0e22\u0e23\u0e4c\u0e2e\u0e2d\u0e25\u0e25\u0e4c \u0e0a\u0e31\u0e49\u0e19 5 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e40\u0e2d\u0e47\u0e21\u0e2a\u0e40\u0e1f\u0e35\u0e22\u0e23\u0e4c \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 26 \u0e1e\u0e24\u0e28\u0e08\u0e34\u0e01\u0e32\u0e22\u0e19 \u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e21\u0e32<\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>\u0e01\u0e23\u0e30\u0e41\u0e2a\u0e1b\u0e31\u0e07\u0e41\u0e25\u0e30\u0e41\u0e23\u0e07\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e44\u0e21\u0e48\u0e2b\u0e22\u0e38\u0e14 \u0e41\u0e21\u0e49\u0e27\u0e48\u0e32\u0e0b\u0e35\u0e23\u0e35\u0e2a\u0e4c\u0e08\u0e30\u0e08\u0e1a\u0e44\u0e1b\u0e41\u0e25\u0e49\u0e27 \u0e41\u0e15\u0e48\u0e17\u0e35\u0e21\u0e19\u0e31\u0e01\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e38\u0e14\u0e2e\u0e2d\u0e15\u0e01\u0e47\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e44\u0e1b\u0e1e\u0e1a\u0e01\u0e31\u0e1a\u0e41\u0e1f\u0e19 \u0e46 \u0e17\u0e31\u0e48\u0e27\u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22 \u0e01\u0e31\u0e1a\u0e07\u0e32\u0e19\u00a0\u201cWE ARE FOREVER ASIA TOUR\u201d\u00a0WE ARE&#8230;\u00a0\u0e40\u0e1e\u0e23\u0e32\u0e30\u0e04\u0e27\u0e32\u0e21\u0e23\u0e31\u0e01\u0e17\u0e35\u0e48\u0e17\u0e38\u0e01\u0e04\u0e19\u0e21\u0e2d\u0e1a\u0e43\u0e2b\u0e49 \u0e08\u0e30\u0e19\u0e32\u0e19\u0e15\u0e25\u0e2d\u0e14\u0e01\u0e32\u0e25\u00a0\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e0b\u0e35\u0e23\u0e35\u0e2a\u0e4c\u00a0\u201cWe Are\u00a0\u0e04\u0e37\u0e2d\u0e40\u0e23\u0e32\u0e23\u0e31\u0e01\u0e01\u0e31\u0e19\u201d\u00a0\u0e08\u0e32\u0e01\u00a0\u201cGMMTV\u201d\u00a0\u0e04\u0e2d\u0e19\u0e40\u0e17\u0e19\u0e15\u0e4c\u0e42\u0e1e\u0e23\u0e44\u0e27\u0e40\u0e14\u0e2d\u0e23\u0e4c\u0e0a\u0e31\u0e49\u0e19\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e44\u0e17\u0e22\u00a0\u0e43\u0e19\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u00a0\u201c\u0e40\u0e14\u0e2d\u0e30 \u0e27\u0e31\u0e19 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 (\u0e21\u0e2b\u0e32\u0e0a\u0e19)\u201d\u00a0\u0e17\u0e35\u0e48\u0e1c\u0e25\u0e34\u0e15\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07 \u0e08\u0e19\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e19\u0e34\u0e22\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e0a\u0e37\u0e48\u0e19\u0e0a\u0e2d\u0e1a\u0e17\u0e31\u0e49\u0e07\u0e08\u0e32\u0e01\u0e41\u0e1f\u0e19 \u0e46 \u0e0a\u0e32\u0e27\u0e44\u0e17\u0e22\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e0a\u0e32\u0e15\u0e34 \u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14\u0e40\u0e02\u0e49\u0e32\u0e15\u0e32\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e04\u0e27\u0e49\u0e32\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u00a0\u201cD-Series\u201d\u00a0\u0e08\u0e32\u0e01\u0e40\u0e27\u0e17\u0e35\u00a0\u201cDailynews Awards 2024\u201d\u00a0\u0e08\u0e31\u0e14\u0e42\u0e14\u0e22\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e40\u0e14\u0e25\u0e34\u0e19\u0e34\u0e27\u0e2a\u0e4c \u0e0b\u0e36\u0e48\u0e07\u0e19\u0e31\u0e01\u0e41\u0e2a\u0e14\u0e07\u0e15\u0e34\u0e14\u0e20\u0e32\u0e23\u0e01\u0e34\u0e08\u0e44\u0e21\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e44\u0e1b\u0e23\u0e31\u0e1a\u0e44\u0e14\u0e49\u0e14\u0e49\u0e27\u0e22\u0e15\u0e19\u0e40\u0e2d\u0e07 \u0e42\u0e14\u0e22\u0e21\u0e35\u00a0\u201c\u0e1b\u0e2d\u0e19\u0e14\u0e4c \u0e13\u0e23\u0e32\u0e27\u0e34\u0e0a\u0e0d\u0e4c \u0e40\u0e25\u0e34\u0e28\u0e23\u0e31\u0e15\u0e19\u0e4c\u0e42\u0e01\u0e2a\u0e38\u0e21\u0e20\u0e4c, \u0e20\u0e39\u0e27\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e15\u0e31\u0e49\u0e07\u0e28\u0e31\u0e01\u0e14\u0e34\u0e4c\u0e22\u0e37\u0e19\u201d\u00a0\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e2a\u0e48\u0e07\u0e04\u0e25\u0e34\u0e1b\u0e01\u0e25\u0e48\u0e32\u0e27\u0e02\u0e2d\u0e1a\u0e04\u0e38\u0e13\u00a0\u0e0b\u0e36\u0e48\u0e07\u0e01\u0e32\u0e23\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e43\u0e19\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e17\u0e31\u0e49\u0e07\u0e19\u0e31\u0e01\u0e41\u0e2a\u0e14\u0e07\u0e41\u0e25\u0e30\u0e17\u0e35\u0e21\u0e07\u0e32\u0e19\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e14\u0e35\u0e43\u0e08\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e32\u0e01 \u0e16\u0e37\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e23\u0e07\u0e1c\u0e25\u0e31\u0e01\u0e14\u0e31\u0e19\u0e43\u0e2b\u0e49\u0e21\u0e35\u0e01\u0e33\u0e25\u0e31\u0e07\u0e43\u0e08\u0e43\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e14\u0e35\u0e22\u0e34\u0e48\u0e07\u0e02\u0e36\u0e49\u0e19 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e02\u0e2d\u0e1a\u0e04\u0e38\u0e13\u0e41\u0e1f\u0e19 \u0e46 \u0e17\u0e35\u0e48\u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e14\u0e49\u0e27\u0e22\u0e14\u0e35\u0e21\u0e32\u0e15\u0e25\u0e2d\u0e14 \u0e13 \u0e2a\u0e40\u0e1f\u0e35\u0e22\u0e23\u0e4c\u0e2e\u0e2d\u0e25\u0e25\u0e4c \u0e0a\u0e31\u0e49\u0e19 5 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e40\u0e2d\u0e47\u0e21\u0e2a\u0e40\u0e1f\u0e35\u0e22\u0e23\u0e4c \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 26 \u0e1e\u0e24\u0e28\u0e08\u0e34\u0e01\u0e32\u0e22\u0e19 \u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e21\u0e32<\/p>","protected":false},"author":8,"featured_media":5538,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[2,10],"tags":[],"class_list":["post-5537","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-corporate-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0e1b\u0e31\u0e07\u0e44\u0e21\u0e48\u0e2b\u0e22\u0e38\u0e14! \u0e0b\u0e35\u0e23\u0e35\u0e2a\u0e4c \u201cWe Are \u0e04\u0e37\u0e2d\u0e40\u0e23\u0e32\u0e23\u0e31\u0e01\u0e01\u0e31\u0e19\u201d \u0e04\u0e27\u0e49\u0e32\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25 \u201cD-Series\u201d \u0e08\u0e32\u0e01\u0e40\u0e27\u0e17\u0e35 \u201cDailynews Awards 2024\u201d - The One Enterprise<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.theoneenterprise.com\/en\/weare_281124\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e1b\u0e31\u0e07\u0e44\u0e21\u0e48\u0e2b\u0e22\u0e38\u0e14! \u0e0b\u0e35\u0e23\u0e35\u0e2a\u0e4c \u201cWe Are \u0e04\u0e37\u0e2d\u0e40\u0e23\u0e32\u0e23\u0e31\u0e01\u0e01\u0e31\u0e19\u201d \u0e04\u0e27\u0e49\u0e32\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25 \u201cD-Series\u201d \u0e08\u0e32\u0e01\u0e40\u0e27\u0e17\u0e35 \u201cDailynews Awards 2024\u201d - The One Enterprise\" \/>\n<meta property=\"og:description\" content=\"\u0e01\u0e23\u0e30\u0e41\u0e2a\u0e1b\u0e31\u0e07\u0e41\u0e25\u0e30\u0e41\u0e23\u0e07\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e44\u0e21\u0e48\u0e2b\u0e22\u0e38\u0e14 \u0e41\u0e21\u0e49\u0e27\u0e48\u0e32\u0e0b\u0e35\u0e23\u0e35\u0e2a\u0e4c\u0e08\u0e30\u0e08\u0e1a\u0e44\u0e1b\u0e41\u0e25\u0e49\u0e27 \u0e41\u0e15\u0e48\u0e17\u0e35\u0e21\u0e19\u0e31\u0e01\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e38\u0e14\u0e2e\u0e2d\u0e15\u0e01\u0e47\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e44\u0e1b\u0e1e\u0e1a\u0e01\u0e31\u0e1a\u0e41\u0e1f\u0e19 \u0e46 \u0e17\u0e31\u0e48\u0e27\u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22 \u0e01\u0e31\u0e1a\u0e07\u0e32\u0e19\u00a0\u201cWE ARE FOREVER ASIA TOUR\u201d\u00a0WE ARE&#8230;\u00a0\u0e40\u0e1e\u0e23\u0e32\u0e30\u0e04\u0e27\u0e32\u0e21\u0e23\u0e31\u0e01\u0e17\u0e35\u0e48\u0e17\u0e38\u0e01\u0e04\u0e19\u0e21\u0e2d\u0e1a\u0e43\u0e2b\u0e49 \u0e08\u0e30\u0e19\u0e32\u0e19\u0e15\u0e25\u0e2d\u0e14\u0e01\u0e32\u0e25\u00a0\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e0b\u0e35\u0e23\u0e35\u0e2a\u0e4c\u00a0\u201cWe Are\u00a0\u0e04\u0e37\u0e2d\u0e40\u0e23\u0e32\u0e23\u0e31\u0e01\u0e01\u0e31\u0e19\u201d\u00a0\u0e08\u0e32\u0e01\u00a0\u201cGMMTV\u201d\u00a0\u0e04\u0e2d\u0e19\u0e40\u0e17\u0e19\u0e15\u0e4c\u0e42\u0e1e\u0e23\u0e44\u0e27\u0e40\u0e14\u0e2d\u0e23\u0e4c\u0e0a\u0e31\u0e49\u0e19\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e44\u0e17\u0e22\u00a0\u0e43\u0e19\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u00a0\u201c\u0e40\u0e14\u0e2d\u0e30 \u0e27\u0e31\u0e19 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 (\u0e21\u0e2b\u0e32\u0e0a\u0e19)\u201d\u00a0\u0e17\u0e35\u0e48\u0e1c\u0e25\u0e34\u0e15\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07 \u0e08\u0e19\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e19\u0e34\u0e22\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e0a\u0e37\u0e48\u0e19\u0e0a\u0e2d\u0e1a\u0e17\u0e31\u0e49\u0e07\u0e08\u0e32\u0e01\u0e41\u0e1f\u0e19 \u0e46 \u0e0a\u0e32\u0e27\u0e44\u0e17\u0e22\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e0a\u0e32\u0e15\u0e34 \u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14\u0e40\u0e02\u0e49\u0e32\u0e15\u0e32\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e04\u0e27\u0e49\u0e32\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u00a0\u201cD-Series\u201d\u00a0\u0e08\u0e32\u0e01\u0e40\u0e27\u0e17\u0e35\u00a0\u201cDailynews Awards 2024\u201d\u00a0\u0e08\u0e31\u0e14\u0e42\u0e14\u0e22\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e40\u0e14\u0e25\u0e34\u0e19\u0e34\u0e27\u0e2a\u0e4c \u0e0b\u0e36\u0e48\u0e07\u0e19\u0e31\u0e01\u0e41\u0e2a\u0e14\u0e07\u0e15\u0e34\u0e14\u0e20\u0e32\u0e23\u0e01\u0e34\u0e08\u0e44\u0e21\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e44\u0e1b\u0e23\u0e31\u0e1a\u0e44\u0e14\u0e49\u0e14\u0e49\u0e27\u0e22\u0e15\u0e19\u0e40\u0e2d\u0e07 \u0e42\u0e14\u0e22\u0e21\u0e35\u00a0\u201c\u0e1b\u0e2d\u0e19\u0e14\u0e4c \u0e13\u0e23\u0e32\u0e27\u0e34\u0e0a\u0e0d\u0e4c \u0e40\u0e25\u0e34\u0e28\u0e23\u0e31\u0e15\u0e19\u0e4c\u0e42\u0e01\u0e2a\u0e38\u0e21\u0e20\u0e4c, \u0e20\u0e39\u0e27\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e15\u0e31\u0e49\u0e07\u0e28\u0e31\u0e01\u0e14\u0e34\u0e4c\u0e22\u0e37\u0e19\u201d\u00a0\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e2a\u0e48\u0e07\u0e04\u0e25\u0e34\u0e1b\u0e01\u0e25\u0e48\u0e32\u0e27\u0e02\u0e2d\u0e1a\u0e04\u0e38\u0e13\u00a0\u0e0b\u0e36\u0e48\u0e07\u0e01\u0e32\u0e23\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e43\u0e19\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e17\u0e31\u0e49\u0e07\u0e19\u0e31\u0e01\u0e41\u0e2a\u0e14\u0e07\u0e41\u0e25\u0e30\u0e17\u0e35\u0e21\u0e07\u0e32\u0e19\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e14\u0e35\u0e43\u0e08\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e32\u0e01 \u0e16\u0e37\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e23\u0e07\u0e1c\u0e25\u0e31\u0e01\u0e14\u0e31\u0e19\u0e43\u0e2b\u0e49\u0e21\u0e35\u0e01\u0e33\u0e25\u0e31\u0e07\u0e43\u0e08\u0e43\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e14\u0e35\u0e22\u0e34\u0e48\u0e07\u0e02\u0e36\u0e49\u0e19 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e02\u0e2d\u0e1a\u0e04\u0e38\u0e13\u0e41\u0e1f\u0e19 \u0e46 \u0e17\u0e35\u0e48\u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e14\u0e49\u0e27\u0e22\u0e14\u0e35\u0e21\u0e32\u0e15\u0e25\u0e2d\u0e14 \u0e13 \u0e2a\u0e40\u0e1f\u0e35\u0e22\u0e23\u0e4c\u0e2e\u0e2d\u0e25\u0e25\u0e4c \u0e0a\u0e31\u0e49\u0e19 5 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e40\u0e2d\u0e47\u0e21\u0e2a\u0e40\u0e1f\u0e35\u0e22\u0e23\u0e4c \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 26 \u0e1e\u0e24\u0e28\u0e08\u0e34\u0e01\u0e32\u0e22\u0e19 \u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e21\u0e32\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.theoneenterprise.com\/en\/weare_281124\/\" \/>\n<meta property=\"og:site_name\" content=\"The One Enterprise\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-28T05:38:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.theoneenterprise.com\/wp-content\/uploads\/2024\/11\/TN_onee-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"manatsanan\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"manatsanan\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.theoneenterprise.com\\\/weare_281124\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.theoneenterprise.com\\\/weare_281124\\\/\"},\"author\":{\"name\":\"manatsanan\",\"@id\":\"https:\\\/\\\/www.theoneenterprise.com\\\/th\\\/#\\\/schema\\\/person\\\/4272b479c4b6118ed078e00f26dbff29\"},\"headline\":\"\u0e1b\u0e31\u0e07\u0e44\u0e21\u0e48\u0e2b\u0e22\u0e38\u0e14! \u0e0b\u0e35\u0e23\u0e35\u0e2a\u0e4c \u201cWe Are \u0e04\u0e37\u0e2d\u0e40\u0e23\u0e32\u0e23\u0e31\u0e01\u0e01\u0e31\u0e19\u201d \u0e04\u0e27\u0e49\u0e32\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25 \u201cD-Series\u201d \u0e08\u0e32\u0e01\u0e40\u0e27\u0e17\u0e35 \u201cDailynews Awards 2024\u201d\",\"datePublished\":\"2024-11-28T05:38:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.theoneenterprise.com\\\/weare_281124\\\/\"},\"wordCount\":18,\"publisher\":{\"@id\":\"https:\\\/\\\/www.theoneenterprise.com\\\/th\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.theoneenterprise.com\\\/weare_281124\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.theoneenterprise.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/TN_onee-2.jpg\",\"articleSection\":[\"News\",\"Corporate News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.theoneenterprise.com\\\/weare_281124\\\/\",\"url\":\"https:\\\/\\\/www.theoneenterprise.com\\\/weare_281124\\\/\",\"name\":\"\u0e1b\u0e31\u0e07\u0e44\u0e21\u0e48\u0e2b\u0e22\u0e38\u0e14! \u0e0b\u0e35\u0e23\u0e35\u0e2a\u0e4c \u201cWe Are \u0e04\u0e37\u0e2d\u0e40\u0e23\u0e32\u0e23\u0e31\u0e01\u0e01\u0e31\u0e19\u201d \u0e04\u0e27\u0e49\u0e32\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25 \u201cD-Series\u201d \u0e08\u0e32\u0e01\u0e40\u0e27\u0e17\u0e35 \u201cDailynews Awards 2024\u201d - The One Enterprise\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.theoneenterprise.com\\\/th\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.theoneenterprise.com\\\/weare_281124\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.theoneenterprise.com\\\/weare_281124\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.theoneenterprise.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/TN_onee-2.jpg\",\"datePublished\":\"2024-11-28T05:38:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.theoneenterprise.com\\\/weare_281124\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.theoneenterprise.com\\\/weare_281124\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.theoneenterprise.com\\\/weare_281124\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.theoneenterprise.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/TN_onee-2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.theoneenterprise.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/TN_onee-2.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.theoneenterprise.com\\\/weare_281124\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.theoneenterprise.com\\\/th\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e1b\u0e31\u0e07\u0e44\u0e21\u0e48\u0e2b\u0e22\u0e38\u0e14! \u0e0b\u0e35\u0e23\u0e35\u0e2a\u0e4c \u201cWe Are \u0e04\u0e37\u0e2d\u0e40\u0e23\u0e32\u0e23\u0e31\u0e01\u0e01\u0e31\u0e19\u201d \u0e04\u0e27\u0e49\u0e32\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25 \u201cD-Series\u201d \u0e08\u0e32\u0e01\u0e40\u0e27\u0e17\u0e35 \u201cDailynews Awards 2024\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.theoneenterprise.com\\\/th\\\/#website\",\"url\":\"https:\\\/\\\/www.theoneenterprise.com\\\/th\\\/\",\"name\":\"The One Enterprise\",\"description\":\"Content creator and distribution company\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.theoneenterprise.com\\\/th\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.theoneenterprise.com\\\/th\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.theoneenterprise.com\\\/th\\\/#organization\",\"name\":\"The One Enterprise\",\"url\":\"https:\\\/\\\/www.theoneenterprise.com\\\/th\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.theoneenterprise.com\\\/th\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.theoneenterprise.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/hero-banner-img-1-pc.jpg\",\"contentUrl\":\"https:\\\/\\\/www.theoneenterprise.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/hero-banner-img-1-pc.jpg\",\"width\":2560,\"height\":1620,\"caption\":\"The One Enterprise\"},\"image\":{\"@id\":\"https:\\\/\\\/www.theoneenterprise.com\\\/th\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.theoneenterprise.com\\\/th\\\/#\\\/schema\\\/person\\\/4272b479c4b6118ed078e00f26dbff29\",\"name\":\"manatsanan\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e1b\u0e31\u0e07\u0e44\u0e21\u0e48\u0e2b\u0e22\u0e38\u0e14! \u0e0b\u0e35\u0e23\u0e35\u0e2a\u0e4c \u201cWe Are \u0e04\u0e37\u0e2d\u0e40\u0e23\u0e32\u0e23\u0e31\u0e01\u0e01\u0e31\u0e19\u201d \u0e04\u0e27\u0e49\u0e32\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25 \u201cD-Series\u201d \u0e08\u0e32\u0e01\u0e40\u0e27\u0e17\u0e35 \u201cDailynews Awards 2024\u201d - The One Enterprise","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.theoneenterprise.com\/en\/weare_281124\/","og_locale":"en_US","og_type":"article","og_title":"\u0e1b\u0e31\u0e07\u0e44\u0e21\u0e48\u0e2b\u0e22\u0e38\u0e14! \u0e0b\u0e35\u0e23\u0e35\u0e2a\u0e4c \u201cWe Are \u0e04\u0e37\u0e2d\u0e40\u0e23\u0e32\u0e23\u0e31\u0e01\u0e01\u0e31\u0e19\u201d \u0e04\u0e27\u0e49\u0e32\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25 \u201cD-Series\u201d \u0e08\u0e32\u0e01\u0e40\u0e27\u0e17\u0e35 \u201cDailynews Awards 2024\u201d - The One Enterprise","og_description":"\u0e01\u0e23\u0e30\u0e41\u0e2a\u0e1b\u0e31\u0e07\u0e41\u0e25\u0e30\u0e41\u0e23\u0e07\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e44\u0e21\u0e48\u0e2b\u0e22\u0e38\u0e14 \u0e41\u0e21\u0e49\u0e27\u0e48\u0e32\u0e0b\u0e35\u0e23\u0e35\u0e2a\u0e4c\u0e08\u0e30\u0e08\u0e1a\u0e44\u0e1b\u0e41\u0e25\u0e49\u0e27 \u0e41\u0e15\u0e48\u0e17\u0e35\u0e21\u0e19\u0e31\u0e01\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e38\u0e14\u0e2e\u0e2d\u0e15\u0e01\u0e47\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e44\u0e1b\u0e1e\u0e1a\u0e01\u0e31\u0e1a\u0e41\u0e1f\u0e19 \u0e46 \u0e17\u0e31\u0e48\u0e27\u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22 \u0e01\u0e31\u0e1a\u0e07\u0e32\u0e19\u00a0\u201cWE ARE FOREVER ASIA TOUR\u201d\u00a0WE ARE&#8230;\u00a0\u0e40\u0e1e\u0e23\u0e32\u0e30\u0e04\u0e27\u0e32\u0e21\u0e23\u0e31\u0e01\u0e17\u0e35\u0e48\u0e17\u0e38\u0e01\u0e04\u0e19\u0e21\u0e2d\u0e1a\u0e43\u0e2b\u0e49 \u0e08\u0e30\u0e19\u0e32\u0e19\u0e15\u0e25\u0e2d\u0e14\u0e01\u0e32\u0e25\u00a0\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e0b\u0e35\u0e23\u0e35\u0e2a\u0e4c\u00a0\u201cWe Are\u00a0\u0e04\u0e37\u0e2d\u0e40\u0e23\u0e32\u0e23\u0e31\u0e01\u0e01\u0e31\u0e19\u201d\u00a0\u0e08\u0e32\u0e01\u00a0\u201cGMMTV\u201d\u00a0\u0e04\u0e2d\u0e19\u0e40\u0e17\u0e19\u0e15\u0e4c\u0e42\u0e1e\u0e23\u0e44\u0e27\u0e40\u0e14\u0e2d\u0e23\u0e4c\u0e0a\u0e31\u0e49\u0e19\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e44\u0e17\u0e22\u00a0\u0e43\u0e19\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u00a0\u201c\u0e40\u0e14\u0e2d\u0e30 \u0e27\u0e31\u0e19 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 (\u0e21\u0e2b\u0e32\u0e0a\u0e19)\u201d\u00a0\u0e17\u0e35\u0e48\u0e1c\u0e25\u0e34\u0e15\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07 \u0e08\u0e19\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e19\u0e34\u0e22\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e0a\u0e37\u0e48\u0e19\u0e0a\u0e2d\u0e1a\u0e17\u0e31\u0e49\u0e07\u0e08\u0e32\u0e01\u0e41\u0e1f\u0e19 \u0e46 \u0e0a\u0e32\u0e27\u0e44\u0e17\u0e22\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e0a\u0e32\u0e15\u0e34 \u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14\u0e40\u0e02\u0e49\u0e32\u0e15\u0e32\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e04\u0e27\u0e49\u0e32\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u00a0\u201cD-Series\u201d\u00a0\u0e08\u0e32\u0e01\u0e40\u0e27\u0e17\u0e35\u00a0\u201cDailynews Awards 2024\u201d\u00a0\u0e08\u0e31\u0e14\u0e42\u0e14\u0e22\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e40\u0e14\u0e25\u0e34\u0e19\u0e34\u0e27\u0e2a\u0e4c \u0e0b\u0e36\u0e48\u0e07\u0e19\u0e31\u0e01\u0e41\u0e2a\u0e14\u0e07\u0e15\u0e34\u0e14\u0e20\u0e32\u0e23\u0e01\u0e34\u0e08\u0e44\u0e21\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e44\u0e1b\u0e23\u0e31\u0e1a\u0e44\u0e14\u0e49\u0e14\u0e49\u0e27\u0e22\u0e15\u0e19\u0e40\u0e2d\u0e07 \u0e42\u0e14\u0e22\u0e21\u0e35\u00a0\u201c\u0e1b\u0e2d\u0e19\u0e14\u0e4c \u0e13\u0e23\u0e32\u0e27\u0e34\u0e0a\u0e0d\u0e4c \u0e40\u0e25\u0e34\u0e28\u0e23\u0e31\u0e15\u0e19\u0e4c\u0e42\u0e01\u0e2a\u0e38\u0e21\u0e20\u0e4c, \u0e20\u0e39\u0e27\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e15\u0e31\u0e49\u0e07\u0e28\u0e31\u0e01\u0e14\u0e34\u0e4c\u0e22\u0e37\u0e19\u201d\u00a0\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e2a\u0e48\u0e07\u0e04\u0e25\u0e34\u0e1b\u0e01\u0e25\u0e48\u0e32\u0e27\u0e02\u0e2d\u0e1a\u0e04\u0e38\u0e13\u00a0\u0e0b\u0e36\u0e48\u0e07\u0e01\u0e32\u0e23\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e43\u0e19\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e17\u0e31\u0e49\u0e07\u0e19\u0e31\u0e01\u0e41\u0e2a\u0e14\u0e07\u0e41\u0e25\u0e30\u0e17\u0e35\u0e21\u0e07\u0e32\u0e19\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e14\u0e35\u0e43\u0e08\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e32\u0e01 \u0e16\u0e37\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e23\u0e07\u0e1c\u0e25\u0e31\u0e01\u0e14\u0e31\u0e19\u0e43\u0e2b\u0e49\u0e21\u0e35\u0e01\u0e33\u0e25\u0e31\u0e07\u0e43\u0e08\u0e43\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e14\u0e35\u0e22\u0e34\u0e48\u0e07\u0e02\u0e36\u0e49\u0e19 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e02\u0e2d\u0e1a\u0e04\u0e38\u0e13\u0e41\u0e1f\u0e19 \u0e46 \u0e17\u0e35\u0e48\u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e14\u0e49\u0e27\u0e22\u0e14\u0e35\u0e21\u0e32\u0e15\u0e25\u0e2d\u0e14 \u0e13 \u0e2a\u0e40\u0e1f\u0e35\u0e22\u0e23\u0e4c\u0e2e\u0e2d\u0e25\u0e25\u0e4c \u0e0a\u0e31\u0e49\u0e19 5 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e40\u0e2d\u0e47\u0e21\u0e2a\u0e40\u0e1f\u0e35\u0e22\u0e23\u0e4c \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 26 \u0e1e\u0e24\u0e28\u0e08\u0e34\u0e01\u0e32\u0e22\u0e19 \u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e21\u0e32","og_url":"https:\/\/www.theoneenterprise.com\/en\/weare_281124\/","og_site_name":"The One Enterprise","article_published_time":"2024-11-28T05:38:58+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/www.theoneenterprise.com\/wp-content\/uploads\/2024\/11\/TN_onee-2.jpg","type":"image\/jpeg"}],"author":"manatsanan","twitter_card":"summary_large_image","twitter_misc":{"Written by":"manatsanan"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.theoneenterprise.com\/weare_281124\/#article","isPartOf":{"@id":"https:\/\/www.theoneenterprise.com\/weare_281124\/"},"author":{"name":"manatsanan","@id":"https:\/\/www.theoneenterprise.com\/th\/#\/schema\/person\/4272b479c4b6118ed078e00f26dbff29"},"headline":"\u0e1b\u0e31\u0e07\u0e44\u0e21\u0e48\u0e2b\u0e22\u0e38\u0e14! \u0e0b\u0e35\u0e23\u0e35\u0e2a\u0e4c \u201cWe Are \u0e04\u0e37\u0e2d\u0e40\u0e23\u0e32\u0e23\u0e31\u0e01\u0e01\u0e31\u0e19\u201d \u0e04\u0e27\u0e49\u0e32\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25 \u201cD-Series\u201d \u0e08\u0e32\u0e01\u0e40\u0e27\u0e17\u0e35 \u201cDailynews Awards 2024\u201d","datePublished":"2024-11-28T05:38:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.theoneenterprise.com\/weare_281124\/"},"wordCount":18,"publisher":{"@id":"https:\/\/www.theoneenterprise.com\/th\/#organization"},"image":{"@id":"https:\/\/www.theoneenterprise.com\/weare_281124\/#primaryimage"},"thumbnailUrl":"https:\/\/www.theoneenterprise.com\/wp-content\/uploads\/2024\/11\/TN_onee-2.jpg","articleSection":["News","Corporate News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.theoneenterprise.com\/weare_281124\/","url":"https:\/\/www.theoneenterprise.com\/weare_281124\/","name":"\u0e1b\u0e31\u0e07\u0e44\u0e21\u0e48\u0e2b\u0e22\u0e38\u0e14! \u0e0b\u0e35\u0e23\u0e35\u0e2a\u0e4c \u201cWe Are \u0e04\u0e37\u0e2d\u0e40\u0e23\u0e32\u0e23\u0e31\u0e01\u0e01\u0e31\u0e19\u201d \u0e04\u0e27\u0e49\u0e32\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25 \u201cD-Series\u201d \u0e08\u0e32\u0e01\u0e40\u0e27\u0e17\u0e35 \u201cDailynews Awards 2024\u201d - The One Enterprise","isPartOf":{"@id":"https:\/\/www.theoneenterprise.com\/th\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.theoneenterprise.com\/weare_281124\/#primaryimage"},"image":{"@id":"https:\/\/www.theoneenterprise.com\/weare_281124\/#primaryimage"},"thumbnailUrl":"https:\/\/www.theoneenterprise.com\/wp-content\/uploads\/2024\/11\/TN_onee-2.jpg","datePublished":"2024-11-28T05:38:58+00:00","breadcrumb":{"@id":"https:\/\/www.theoneenterprise.com\/weare_281124\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.theoneenterprise.com\/weare_281124\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.theoneenterprise.com\/weare_281124\/#primaryimage","url":"https:\/\/www.theoneenterprise.com\/wp-content\/uploads\/2024\/11\/TN_onee-2.jpg","contentUrl":"https:\/\/www.theoneenterprise.com\/wp-content\/uploads\/2024\/11\/TN_onee-2.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/www.theoneenterprise.com\/weare_281124\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.theoneenterprise.com\/th\/"},{"@type":"ListItem","position":2,"name":"\u0e1b\u0e31\u0e07\u0e44\u0e21\u0e48\u0e2b\u0e22\u0e38\u0e14! \u0e0b\u0e35\u0e23\u0e35\u0e2a\u0e4c \u201cWe Are \u0e04\u0e37\u0e2d\u0e40\u0e23\u0e32\u0e23\u0e31\u0e01\u0e01\u0e31\u0e19\u201d \u0e04\u0e27\u0e49\u0e32\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25 \u201cD-Series\u201d \u0e08\u0e32\u0e01\u0e40\u0e27\u0e17\u0e35 \u201cDailynews Awards 2024\u201d"}]},{"@type":"WebSite","@id":"https:\/\/www.theoneenterprise.com\/th\/#website","url":"https:\/\/www.theoneenterprise.com\/th\/","name":"The One Enterprise","description":"Content creator and distribution company","publisher":{"@id":"https:\/\/www.theoneenterprise.com\/th\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.theoneenterprise.com\/th\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.theoneenterprise.com\/th\/#organization","name":"The One Enterprise","url":"https:\/\/www.theoneenterprise.com\/th\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.theoneenterprise.com\/th\/#\/schema\/logo\/image\/","url":"https:\/\/www.theoneenterprise.com\/wp-content\/uploads\/2021\/12\/hero-banner-img-1-pc.jpg","contentUrl":"https:\/\/www.theoneenterprise.com\/wp-content\/uploads\/2021\/12\/hero-banner-img-1-pc.jpg","width":2560,"height":1620,"caption":"The One Enterprise"},"image":{"@id":"https:\/\/www.theoneenterprise.com\/th\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.theoneenterprise.com\/th\/#\/schema\/person\/4272b479c4b6118ed078e00f26dbff29","name":"manatsanan"}]}},"_links":{"self":[{"href":"https:\/\/www.theoneenterprise.com\/en\/wp-json\/wp\/v2\/posts\/5537","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.theoneenterprise.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.theoneenterprise.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.theoneenterprise.com\/en\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.theoneenterprise.com\/en\/wp-json\/wp\/v2\/comments?post=5537"}],"version-history":[{"count":0,"href":"https:\/\/www.theoneenterprise.com\/en\/wp-json\/wp\/v2\/posts\/5537\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.theoneenterprise.com\/en\/wp-json\/wp\/v2\/media\/5538"}],"wp:attachment":[{"href":"https:\/\/www.theoneenterprise.com\/en\/wp-json\/wp\/v2\/media?parent=5537"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.theoneenterprise.com\/en\/wp-json\/wp\/v2\/categories?post=5537"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.theoneenterprise.com\/en\/wp-json\/wp\/v2\/tags?post=5537"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}